
{"id":501,"date":"2024-11-09T11:25:06","date_gmt":"2024-11-09T10:25:06","guid":{"rendered":"https:\/\/play-rugby.com\/?p=501"},"modified":"2025-05-27T12:41:38","modified_gmt":"2025-05-27T10:41:38","slug":"xv-les-bleus-vont-ils-nous-reconcilier-avec-le-rugby-pendant-la-tournee-dautomne","status":"publish","type":"post","link":"https:\/\/www.play-rugby.com\/index.php\/2024\/11\/09\/xv-les-bleus-vont-ils-nous-reconcilier-avec-le-rugby-pendant-la-tournee-dautomne\/","title":{"rendered":"XV: Les Bleus vont-ils nous r\u00e9concilier avec le rugby pendant la tourn\u00e9e d\u2019automne ?"},"content":{"rendered":"<h1>France &#8211; Japon<\/h1>\n<p>Les hommes de Fabien Galthi\u00e9 affrontent le Japon pour lancer la tourn\u00e9e d\u2019automne, marqu\u00e9e par le retour d\u2019Antoine Dupont avec le XV de France. L\u2019occasion de trouver des raisons de s\u2019enthousiasmer pour du rugby (ou pas)<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.20minutes.fr\/sport\/rugby\/4120335-20241109-xv-france-bleus-vont-reconcilier-rugby-pendant-tournee-automne?xtor=EPR-212-[nl%20sport]---f0359d5b996af3f72d7c57d2776ba1aa@2&amp;utm_source=newsletter&amp;utm_medium=email&amp;utm_campaign=sport&amp;_ope=eyJndWlkIjoiZjAzNTlkNWI5OTZhZjNmNzJkN2M1N2QyNzc2YmExYWEifQ%3D%3D\">Lire l&#8217;Article dans 20minutes<\/a><\/span><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Le XV de France lance sa tourn\u00e9e d\u2019automne ce samedi au Stade de France contre le Japon&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[23],"tags":[51],"class_list":["post-501","post","type-post","status-publish","format-standard","hentry","category-news","tag-japon","comments-off"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":2,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":621,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/501\/revisions\/621"}],"wp:attachment":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}