
{"id":495,"date":"2024-10-25T10:53:09","date_gmt":"2024-10-25T08:53:09","guid":{"rendered":"https:\/\/play-rugby.com\/?p=495"},"modified":"2025-05-27T12:42:08","modified_gmt":"2025-05-27T10:42:08","slug":"xv-oui-il-y-a-eu-des-abus-non-tolerables-admet-fabien-galthie","status":"publish","type":"post","link":"https:\/\/www.play-rugby.com\/index.php\/2024\/10\/25\/xv-oui-il-y-a-eu-des-abus-non-tolerables-admet-fabien-galthie\/","title":{"rendered":"XV: \u00ab Oui, il y a eu des abus non tol\u00e9rables \u00bb, admet Fabien Galthi\u00e9"},"content":{"rendered":"<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.20minutes.fr\/sport\/rugby\/4117738-20241025-xv-france-oui-abus-non-tolerables-admet-fabien-galthie-instaure-nouveau-cadre-vie?xtor=EPR-212-[nl%20sport]---f0359d5b996af3f72d7c57d2776ba1aa@2&amp;utm_source=newsletter&amp;utm_medium=email&amp;utm_campaign=sport&amp;_ope=eyJndWlkIjoiZjAzNTlkNWI5OTZhZjNmNzJkN2M1N2QyNzc2YmExYWEifQ%3D%3D\">L&#8217;ARTICLE DE 20minutes<\/a><\/h1>\n<p>Les cicatrices ouvertes lors de la tourn\u00e9e d\u2019\u00e9t\u00e9 en Argentine et en Uruguay mettront sans doute un peu de temps \u00e0 cicatriser.<\/p>\n<p>Apr\u00e8s les insultes racistes de <strong>Melvyn Jaminet<\/strong> et la mise en examen pour viol d\u2019<strong>Oscar Jegou et Hugo Auradou<\/strong>, le rugby fran\u00e7ais a pris un coup sur la t\u00eate. Et s\u2019est lanc\u00e9 dans son introspection pour \u00e9viter que de pareils d\u00e9lits ne se reproduisent. C\u2019est dans cet objectif que, en amont de la tourn\u00e9e automnale, <strong>Fabien Galthi\u00e9<\/strong> a pr\u00e9par\u00e9 un nouveau cadre de vie pour le XV de France.<\/p>\n<p>L\u2019alcool, sans autorisation y sera d\u00e9sormais interdit, tout comme la pr\u00e9sence de personnes \u00e9trang\u00e8res, l\u00e0 aussi sans autorisation pr\u00e9alable et l\u2019autom\u00e9dication devra \u00eatre d\u00e9clar\u00e9e, indique le s\u00e9lectionneur des Bleus dans une interview accord\u00e9e \u00e0 L\u2019Equipe. L\u2019ancien demi de m\u00eal\u00e9e explique qu&#8217;\u00ab <em>une remise en question profonde est n\u00e9cessaire, parce que toutes ces coutumes [de la troisi\u00e8me mi-temps], c\u2019est tr\u00e8s ancr\u00e9. [\u2026] S\u00fbrement qu\u2019il y a eu des abus dans le cadre de coutumes existantes \u00bb.<\/em><\/p>\n<h3>\u00ab La troisi\u00e8me mi-temps vient tout balayer \u00bb<\/h3>\n<blockquote><p>Fabien Galthi\u00e9 estime que lors de la tourn\u00e9e en Argentine, \u00ab il y a eu une moins bonne pr\u00e9paration de ce cadre de vie, avec une \u00e9quipe tr\u00e8s jeune, avec peu d\u2019exp\u00e9rience internationale, une s\u00e9lection faite au dernier moment et une moins bonne connaissance des joueurs. \u00c7a nous a amen\u00e9s \u00e0 ces accidents, ces faits divers. Les faits sont l\u00e0, il n\u2019y a rien \u00e0 dire, ils sont inacceptables. [\u2026] Oui, Il y a eu des abus non tol\u00e9rables ou des erreurs. \u00bb<\/p><\/blockquote>\n<p>L\u2019entra\u00eeneur pass\u00e9 par le Stade Fran\u00e7ais et Toulon estime que la consommation d\u2019alcool, notamment lors de la troisi\u00e8me mi-temps, n\u2019est pas compatible avec le sport de haut niveau :<\/p>\n<blockquote><p>\u00ab Je passe des erreurs \u00e0 \u00e9tudier une strat\u00e9gie, un sc\u00e9nario et finalement, la coutume [la troisi\u00e8me mi-temps] peut tout balayer. On sait que si on fait une soir\u00e9e alcoolis\u00e9e, \u00e7a double l\u2019effet du match niveau d\u00e9shydratation et d\u00e9chet musculaire. Donc tu ne peux pas t\u2019entra\u00eener comme tu l\u2019avais pr\u00e9vu. \u00bb<\/p><\/blockquote>\n<p>Non s\u00e9lectionn\u00e9s lors de cette tourn\u00e9e automnale, Hugo Auradou et Oscar Jegou, qui ont re\u00e7u la visite du s\u00e9lectionneur dans leur club respectif, ne pourront rev\u00eatir le maillot bleu que si un non-lieu \u00e9tait prononc\u00e9, r\u00e9p\u00e8te Galthi\u00e9. Pour Melvyn Jaminet, son avenir en s\u00e9lection semble bouch\u00e9. \u00ab Les propos de Melvyn \u00e9taient choquants et inacceptables \u00bb, r\u00e9p\u00e8te Galthi\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV de France : \u00ab Oui, il y a eu des abus non tol\u00e9rables \u00bb, admet Fabien Galthi\u00e9, qui a instaur\u00e9 un nouveau cadre de vie&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[23],"tags":[50,31],"class_list":["post-495","post","type-post","status-publish","format-standard","hentry","category-news","tag-fabien-galthie","tag-xv","comments-off"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":1,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions"}],"predecessor-version":[{"id":497,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions\/497"}],"wp:attachment":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}