
{"id":491,"date":"2024-10-13T12:12:31","date_gmt":"2024-10-13T10:12:31","guid":{"rendered":"https:\/\/play-rugby.com\/?p=491"},"modified":"2025-05-27T12:57:35","modified_gmt":"2025-05-27T10:57:35","slug":"xv-peniasi-dakuwaqa-la-fusee-fidjienne-du-stade-francais","status":"publish","type":"post","link":"https:\/\/www.play-rugby.com\/index.php\/2024\/10\/13\/xv-peniasi-dakuwaqa-la-fusee-fidjienne-du-stade-francais\/","title":{"rendered":"XV: Peniasi Dakuwaqa, la fus\u00e9e fidjienne du Stade Fran\u00e7ais"},"content":{"rendered":"<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.lequipe.fr\/Rugby\/Article\/Peniasi-dakuwaqa-le-fidjien-qui-ne-jouait-pas-le-samedi\/1513479?xtor=EPR-608&amp;m_i=QtSC08dep4NOS18on%2Bia2Z9M1T7p1usb7DTtVz_pv9Be8jHELbhiJg1SzTyaZkG1w5ZPQpXmbzgkgjH1qedtxLFdqjHBqGMV7YiqQ%2B&amp;M_BT=26744858836961\">LIRE L&#8217;ARTICLE DE L&#8217;EQUIPE<\/a><\/h1>\n<p>Peniasi Dakuwaqa, la fus\u00e9e fidjienne du Stade Fran\u00e7ais qui n&#8217;avait pas le droit de jouer le samedi<br \/>\nTitulaire \u00e0 une aile du Stade Fran\u00e7ais qui va jouer \u00e0 Lyon dimanche soir, arriv\u00e9 \u00e0 Paris \u00e0 25 ans dans l&#8217;anonymat le plus total, l&#8217;ailier fidjien Peniasi Dakuwaqa a perc\u00e9 sur le tard. En cause, notamment, une r\u00e8gle stricte de son grand-p\u00e8re qui lui interdisait de jouer au rugby le samedi.<\/p>\n<p>Un tee-shirt roul\u00e9 en boule et nou\u00e9 par les manches, une bouteille d&#8217;eau ou une noix de coco. C&#8217;est avec ces ballons de fortune, dans un jardin du village de Nagado, \u00e0 Nadi, au nord-ouest de l&#8217;\u00eele principale de Viti Levu aux Fidji, que Peniasi Dakuwaqa (1, 86 m &#8211; 95 kg) a d\u00e9couvert le rugby.<\/p>\n<blockquote><p>\u00ab On n&#8217;avait pas les moyens d&#8217;acheter des vrais ballons, c&#8217;\u00e9tait trop cher, se souvient celui qui a \u00e9t\u00e9 \u00e9duqu\u00e9 par son grand-p\u00e8re avec une vingtaine de cousins au sein d&#8217;une famille sans-le-sou. Quand on jouait avec des voisins, il n&#8217;y avait pas de r\u00e8gle : \u00e7a plaquait \u00e0 la t\u00eate ! D\u00e8s que tu avais le ballon, cinq gamins te fon\u00e7aient dessus pour te d\u00e9couper. C&#8217;est pour \u00e7a qu&#8217;il fallait courir vite. \u00bb<\/p><\/blockquote>\n<p>\u00c7a n&#8217;a jamais \u00e9t\u00e9 un probl\u00e8me pour l&#8217;ailier fidjien de 27 ans. C&#8217;est m\u00eame ce qui a convaincu les dirigeants du Stade Fran\u00e7ais, son directeur g\u00e9n\u00e9ral Thomas Lombard et le patron du recrutement parisien Christophe Moni, de l&#8217;engager en qualit\u00e9 de joker m\u00e9dical, \u00e0 l&#8217;automne 2022, sur les conseils de <strong>Sireli Bobo<\/strong>.<\/p>\n<blockquote><p>\u00ab J&#8217;ai dit \u00e0 Thomas que Peniasi deviendrait leur joueur vedette s&#8217;il me faisait confiance, rembobine l&#8217;ancien international fidjien. Et je lui ai envoy\u00e9 une vid\u00e9o. \u00bb<\/p><\/blockquote>\n<p>Une compilation de cinq minutes des plus belles actions de \u00ab Peni \u00bb, parfois film\u00e9es au t\u00e9l\u00e9phone par sa femme Cheryl, sur un terrain de rugby ou une piste d&#8217;athl\u00e9tisme. En crampons ou en pointes, les chaussettes baiss\u00e9es sous les chevilles, Dakuwaqa y cr\u00e8ve l&#8217;\u00e9cran. Son pouvoir d&#8217;acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nal lui vaudra d&#8217;\u00eatre surnomm\u00e9 \u00ab The Flash \u00bb par le commentateur sportif local Papa Graham.<\/p>\n<blockquote><p>\u00ab Courir vite, c&#8217;est dans mes g\u00e8nes, dit d&#8217;un haussement d&#8217;\u00e9paules timide ce grand gaillard du genre taiseux. Mon p\u00e8re aussi \u00e9tait tr\u00e8s rapide. \u00bb<\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"Peniasi Dakuwaqa Highlights 2020\/2021\" width=\"910\" height=\"512\" src=\"https:\/\/www.youtube.com\/embed\/JtXIawixq_w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>En 2020, Peniasi \u00ab Ben \u00bb Dakuwaqa avait remport\u00e9 la <strong>m\u00e9daille d&#8217;or sur le 100 m\u00e8tres<\/strong> des Jeux des \u00eeles Cook en 10&#8221;42. Il avait alors 23 ans et pas la moindre exp\u00e9rience rugbystique professionnelle. Entre les Fidji et les \u00eeles Cook, o\u00f9 il avait d\u00e9m\u00e9nag\u00e9 pour rejoindre son \u00e9pouse, il avait pourtant touch\u00e9 \u00e0 tout au niveau amateur : rugby \u00e0 7, 9, XIII et quinze, notamment aux Tupapa Maraerenga Panthers.<\/p>\n<blockquote><p>\u00ab J&#8217;ai en m\u00e9moire un match chez le champion en titre, indique <strong>Delaney Yaqona<\/strong>, le manager g\u00e9n\u00e9ral des Panthers. C&#8217;\u00e9tait la premi\u00e8re journ\u00e9e de la saison, on \u00e9tait rouill\u00e9s et il nous manquait beaucoup de joueurs. En plus, il pleuvait. \u00c7a n&#8217;a pas emp\u00each\u00e9 &#8221;Ben&#8221; de marquer quatre essais. \u00c0 chaque fois qu&#8217;il touchait le ballon, il inventait quelque chose. Il \u00e9voluait dans une autre galaxie. \u00bb Pas assez pour que le Fidjien, qui cumulait alors des petits boulots dans la construction, puisse vivre du rugby plus t\u00f4t.<\/p>\n<p>\u00ab J&#8217;ai demand\u00e9 \u00e0 sa tante pourquoi il n&#8217;avait pas \u00e9t\u00e9 rep\u00e9r\u00e9 plus vite malgr\u00e9 son talent, raconte sa <strong>compagne Cheryl.<\/strong> Elle m&#8217;a expliqu\u00e9 qu&#8217;il avait grandi avec un grand-p\u00e8re strict, membre de l&#8217;\u00c9glise adventiste du septi\u00e8me jour. \u00bb<\/p><\/blockquote>\n<p>Tr\u00e8s pratiquant, cet ancien boxeur, qui r\u00e9veillait toute la maison aux aurores en grattant quelques airs de guitare, respectait scrupuleusement les r\u00e8gles de sa religion. \u00ab Tu ne bois pas, tu ne fumes pas \u00bb, r\u00e9cite son petit-fils, dont les journ\u00e9es \u00e9taient rythm\u00e9es par l&#8217;\u00e9cole, la plantation familiale o\u00f9 il cultivait marantes, taros et patates douces, la vente sur les march\u00e9s, la p\u00eache et la pri\u00e8re avant de se coucher.<\/p>\n<blockquote><p>\u00ab Et le samedi, qui est le septi\u00e8me jour, ajoute-t-il, tu ne travailles pas et tu ne fais pas de sport. \u00bb<\/p><\/blockquote>\n<p>Voil\u00e0 pourquoi Dakuwaqa a s\u00e9ch\u00e9 de nombreux matches de rugby pendant des ann\u00e9es.<\/p>\n<blockquote><p>\u00ab Quand mon grand-p\u00e8re est tomb\u00e9 malade, j&#8217;ai arr\u00eat\u00e9 l&#8217;\u00e9cole pour m&#8217;occuper de lui et de la plantation, reprend-il. \u00c0 l&#8217;\u00e9poque, les tournois \u00e9taient sur deux jours. Le vendredi, je l&#8217;amenais au stade, je l&#8217;aidais \u00e0 s&#8217;asseoir en tribunes et je jouais devant lui parce qu&#8217;il aimait me regarder. Mais le samedi, on restait \u00e0 la maison. On ne sortait que pour aller \u00e0 l&#8217;\u00e9glise. \u00bb<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Le joueur, qui a perdu son grand-p\u00e8re en 2020, a pris du retard et manqu\u00e9 des occasions d&#8217;\u00eatre rep\u00e9r\u00e9. L&#8217;offre du Stade Fran\u00e7ais a tout boulevers\u00e9.<\/p>\n<blockquote><p>\u00ab \u00catre ici, c&#8217;est ce que je veux, c&#8217;est mon r\u00eave, affirme-t-il. Je n&#8217;ai pas le choix, je dois y arriver. Peu importe les difficult\u00e9s. \u00bb E<em>lles furent nombreuses \u00e0 son arriv\u00e9e en France. La vie en appartement \u00e0 Boulogne-Billancourt<\/em> &#8211; \u00ab du bruit tout le temps, pas de jardin \u00bb -, le froid &#8211; \u00ab on est arriv\u00e9 avec nos v\u00eatements d&#8217;\u00e9t\u00e9. Le premier matin, je suis sorti en shorts. Tout le monde me regardait comme si j&#8217;\u00e9tais fou \u00bb -, la barri\u00e8re de la langue et la d\u00e9couverte des chaudes ambiances du top 14, \u00e0 l&#8217;instar d&#8217;un d\u00e9placement tendu \u00e0 Bayonne &#8211; \u00ab un mec a renvers\u00e9 sa bi\u00e8re sur Gonzalo (<em>Quesada, l&#8217;ancien entra\u00eeneur du Stade Fran\u00e7ais)<\/em>. Il nous insultait. \u00bb<\/p><\/blockquote>\n<p>Les pi\u00e8ges \u00e0 \u00e9viter, aussi, comme ce premier No\u00ebl pass\u00e9 avec d&#8217;autres joueurs fidjiens en r\u00e9gion parisienne.<\/p>\n<blockquote><p>\u00ab Ils l&#8217;ont fait boire parce que c&#8217;\u00e9tait le petit nouveau, soupire son \u00e9pouse. Quand il est rentr\u00e9, j&#8217;ai failli le foutre \u00e0 la porte. Je ne l&#8217;avais jamais vu comme \u00e7a. J&#8217;\u00e9tais tellement en col\u00e8re&#8230; Les Fidjiens peuvent avoir tendance \u00e0 faire des choses stupides. Mais, nous, on est diff\u00e9rents, ce n&#8217;est pas notre truc. \u00bb \u00ab C&#8217;est la premi\u00e8re et derni\u00e8re fois que j&#8217;y allais, promet son mari. Je ne suis pas venu ici pour \u00e7a. \u00bb<\/p><\/blockquote>\n<p>Dakuwaqa est venu pour jouer au rugby, mais il lui a fallu ronger son frein. Embrasser un r\u00f4le &#8211; ailier \u00e0 XV &#8211; qu&#8217;il connaissait \u00e0 peine et apprivoiser le jeu europ\u00e9en, \u00ab plus structur\u00e9 et tactique \u00bb que ce qu&#8217;il connaissait. Aid\u00e9 au quotidien par Paul Gustard, l&#8217;entra\u00eeneur de la d\u00e9fense, il a pass\u00e9 ses premiers mois sur le banc ou en tribunes. Peu de minutes de jeu et encore moins de ballons \u00e0 exploiter.<\/p>\n<blockquote><p>\u00ab Parfois, je rentrais quinze minutes, je touchais un seul ballon. Et parfois, aucun&#8230; J&#8217;\u00e9tais tellement frustr\u00e9, souffle-t-il. J&#8217;avais juste besoin d&#8217;une opportunit\u00e9. \u00bb<\/p><\/blockquote>\n<p>Elle s&#8217;est pr\u00e9sent\u00e9e en f\u00e9vrier 2023 lors de la r\u00e9ception de Montpellier (27-17).<\/p>\n<blockquote><p>\u00ab Dix minutes avant la mi-temps, Sione Tui s&#8217;est bless\u00e9 et je l&#8217;ai remplac\u00e9, se rem\u00e9more-t-il. C&#8217;\u00e9tait ma chance, le moment que j&#8217;attendais depuis mon arriv\u00e9e. \u00bb \u00ab \u00c7a passait ou \u00e7a cassait, glisse Cheryl. Il a fait son meilleur match et on a sign\u00e9 son contrat pro le lendemain. \u00bb<\/p><\/blockquote>\n<p>Prolong\u00e9 jusqu&#8217;en 2026, Dakuwaqa a depuis encha\u00een\u00e9 les prestations int\u00e9ressantes avec, en point d&#8217;orgue, cet essai du bout du monde sur la pelouse du Racing 92 en f\u00e9vrier dernier, 127 m\u00e8tres d&#8217;une folle course conclue dans l&#8217;en-but.<\/p>\n<p>Laiss\u00e9 hors groupe lors des trois premi\u00e8res journ\u00e9es de Championnat en septembre et peu consid\u00e9r\u00e9 par l&#8217;entra\u00eeneur stadiste Karim Ghezal, remerci\u00e9 depuis, l&#8217;ailier a craint un d\u00e9classement. Ses deux essais, \u00e0 Pau puis contre Montpellier lors de la derni\u00e8re journ\u00e9e, ont mis tout le monde d&#8217;accord : le facteur X du Stade Fran\u00e7ais, c&#8217;est bien lui.<\/p>\n<p>M\u00eame le samedi.<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.lequipe.fr\/Rugby\/Article\/Peniasi-dakuwaqa-le-fidjien-qui-ne-jouait-pas-le-samedi\/1513479?xtor=EPR-608&amp;m_i=QtSC08dep4NOS18on%2Bia2Z9M1T7p1usb7DTtVz_pv9Be8jHELbhiJg1SzTyaZkG1w5ZPQpXmbzgkgjH1qedtxLFdqjHBqGMV7YiqQ%2B&amp;M_BT=26744858836961\">LIRE L&#8217;ARTICLE DE L&#8217;EQUIPE<\/a><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Equipe: Peniasi Dakuwaqa, la fus\u00e9e fidjienne du Stade Fran\u00e7ais n&#8217;avait pas le droit de jouer le samedi \u00e0 cause d&#8217;un grand-p\u00e8re Adventiste du 7e jour&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-491","post","type-post","status-publish","format-standard","hentry","category-non-classe","comments-off"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=491"}],"version-history":[{"count":2,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/491\/revisions"}],"predecessor-version":[{"id":625,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/491\/revisions\/625"}],"wp:attachment":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}