
{"id":480,"date":"2024-09-21T10:22:29","date_gmt":"2024-09-21T08:22:29","guid":{"rendered":"https:\/\/play-rugby.com\/?p=480"},"modified":"2025-05-27T12:54:44","modified_gmt":"2025-05-27T10:54:44","slug":"xv-top-14-comment-se-remettre-en-ordre-apres-une-lourde-defaite","status":"publish","type":"post","link":"https:\/\/www.play-rugby.com\/index.php\/2024\/09\/21\/xv-top-14-comment-se-remettre-en-ordre-apres-une-lourde-defaite\/","title":{"rendered":"XV: Top 14 &#8211; comment se remettre en ordre apr\u00e8s une lourde d\u00e9faite ?"},"content":{"rendered":"<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.lequipe.fr\/Rugby\/Article\/Top-14-comment-se-remettre-en-ordre-apres-une-lourde-defaite\/1509021?xtor=EPR-608&amp;m_i=vHKFgf0yvKdG435ZbuPeq78Wk_4cB8wagEGBkCQ7XkoU1hdrlHUQQSWF4AM3%2BRPNBuEYXIMfnnaskmsvYsqtA%2B7crMCKpUaRfe2IvV&amp;M_BT=26744858836961\">LIRE L&#8217;ARTICLE DANS L&#8217;EQUIPE<\/a><\/h1>\n<p><em>Le d\u00e9but de saison a \u00e9t\u00e9 marqu\u00e9 par certaines roustes. \u00c0 quoi ressemblent les jours qui suivent dans les clubs concern\u00e9s\u00a0? Le mythe de la s\u00e9ance vid\u00e9o \u00e0 l&#8217;aube le lendemain matin semble avoir v\u00e9cu mais les d\u00e9briefings restent \u00ab\u00a0sal\u00e9s\u00a0\u00bb, pour activer notamment le levier de l&#8217;orgueil.<\/em><\/p>\n<p>Jeudi matin au Parc des Sports de Perpignan, l&#8217;ambiance de fin d&#8217;entra\u00eenement est d\u00e9tendue. <strong>Patrick Arlettaz,<\/strong> entra\u00eeneur adjoint du XV de France et ancien manager de l&#8217;USAP, est de passage. Il se fait all\u00e8grement chambrer pour sa chemise rose par ses anciens joueurs.<\/p>\n<p>On est loin de l&#8217;ambiance pesante qui avait suivi la lourde d\u00e9faite \u00e0 \u00ab domicile \u00bb (le match \u00e9tait d\u00e9localis\u00e9 \u00e0 B\u00e9ziers) contre Montpellier (7-26), samedi. \u00c0 chaud, le <strong>manager Franck Az\u00e9ma<\/strong> avait \u00e9voqu\u00e9 sa \u00ab honte \u00bb et encha\u00een\u00e9, ton grave et voix qui porte, les punchlines : \u00ab On s&#8217;est fait d\u00e9foncer \u00bb, \u00ab Sur le rendu, il n&#8217;y a rien, z\u00e9ro \u00bb&#8230; Dans le vestiaire, les premiers mots sont muscl\u00e9s, sorte de mise en bouche du d\u00e9briefing du lundi matin.<\/p>\n<p>Ce retour vid\u00e9o, c&#8217;est visiblement le sale moment \u00e0 passer quand on a d\u00e9gust\u00e9. Les Montpelli\u00e9rains y ont eu droit apr\u00e8s leur d\u00e9faite \u00e0 domicile contre Lyon (22-26, 1re journ\u00e9e), imit\u00e9s au m\u00eame moment par des Palois fess\u00e9s \u00e0 Clermont (39-7) puis la semaine suivante par les Bayonnais lamin\u00e9s \u00e0&#8230; Pau (51-29, 2e j.) et les joueurs de l&#8217;USAP, donc.<\/p>\n<blockquote><p>La seule bonne nouvelle, selon les diff\u00e9rents t\u00e9moignages recueillis cette semaine, c&#8217;est que le d\u00e9brief improvis\u00e9 \u00e0 l&#8217;aube le lendemain matin semble avoir v\u00e9cu.<\/p><\/blockquote>\n<p>L&#8217;expert en la mati\u00e8re \u00e9tait peut-\u00eatre <strong>Bernard Laporte<\/strong> quand il dirigeait Toulon (2011-2016), comme racont\u00e9 dans nos colonnes fin 2017 par Gilles Panzani, l&#8217;intendant de l&#8217;\u00e9poque : \u00ab \u00c0 Bordeaux en 2013, on prend 40 points (41-0). Dans le vestiaire, Bernard Laporte annonce : &#8220;\u00c0 demain 6h30 \u00e0 Berg (lieu du centre d&#8217;entra\u00eenement du RCT) pour la vid\u00e9o&#8221;.<\/p>\n<p>Le lendemain matin, Carl Hayman appelle pour dire qu&#8217;il ne pouvait pas venir car sa femme est en Angleterre et qu&#8217;il n&#8217;a pas de nounou pour ses deux petites. Bernard lui r\u00e9pond : &#8220;Je m&#8217;en branle, t&#8217;as qu&#8217;\u00e0 venir, Panzani gardera les petites&#8221;. Je me suis retrouv\u00e9 avec les deux ! J&#8217;ai fait au moins trente fois le tour du stade avec la poussette. \u00bb Tout le monde en prenait pour son grade, au soleil levant, les courbatures vivaces.<\/p>\n<p>La nouvelle g\u00e9n\u00e9ration d&#8217;entra\u00eeneurs semble moins port\u00e9e sur ce genre de punition collective. \u00ab R\u00e9unir ses joueurs \u00e0 6 heures du matin le lendemain, je ne dis pas c&#8217;est absurde, mais \u00e7a ne peut \u00eatre qu&#8217;une solution dans un moment particulier \u00bb, estime le <strong>manager de Pau S\u00e9bastien Piqueronies<\/strong>.<\/p>\n<blockquote><p>\u00ab Hausser le ton en permanence, \u00e7a ne sert \u00e0 rien, appuie son homologue du LOU Fabien Gengenbacher qui a vu son \u00e9quipe la saison derni\u00e8re encha\u00eener victoires \u00e0 domicile et lourdes d\u00e9faites \u00e0 l&#8217;ext\u00e9rieur. Il y a cinq ou six fen\u00eatres o\u00f9 on peut \u00eatre plus dur dans les mots. Si c&#8217;est plus, je ne suis pas s\u00fbr que les joueurs \u00e9coutent encore. \u00bb<\/p>\n<p>\u00ab Le staff, oui, on se retrouve peut-\u00eatre plus t\u00f4t que pr\u00e9vu, parce qu&#8217;on ne dort pas beaucoup et qu&#8217;on a vite envie de d\u00e9briefer le match et trouver les mots pour remobiliser les joueurs, t\u00e9moigne de son c\u00f4t\u00e9 R\u00e9mi Tal\u00e8s, entra\u00eeneur des trois quarts de La Rochelle. Mais convoquer les joueurs \u00e0 7 heures un lendemain de d\u00e9faite alors qu&#8217;on est parfois rentr\u00e9 tr\u00e8s tard, je ne pense pas que ce soit la meilleure solution pour repartir de l&#8217;avant. \u00bb<\/p><\/blockquote>\n<h3>Des joueurs piqu\u00e9s dans leur orgueil et mis face \u00e0 leurs responsabilit\u00e9s<\/h3>\n<p>La mauvaise nouvelle, c&#8217;est que quand le ton monte, il peut monter tr\u00e8s haut. Comme \u00e0 <strong>Montpellier<\/strong> jeudi dernier quand <strong>Geoffrey Doumayrou<\/strong>, entra\u00eeneur de la d\u00e9fense, m\u00e9content d&#8217;attitudes sur un atelier, a secou\u00e9 ses joueurs. Sans filtre. Comme \u00e0 Bayonne lundi.<\/p>\n<p>\u00ab On a fait un d\u00e9briefing vid\u00e9o qui a \u00e9t\u00e9 plut\u00f4t sal\u00e9 afin de mettre le groupe devant ses responsabilit\u00e9s \u00bb, confirme le manager de l&#8217;Aviron Gr\u00e9gory Patat. \u00ab Franck (Az\u00e9ma) \u00e9tait encore \u00e9nerv\u00e9 lundi matin, glisse de son c\u00f4t\u00e9 le demi de m\u00eal\u00e9e de Perpignan Tom Ecochard. Il nous a dit nos v\u00e9rit\u00e9s, le d\u00e9but de semaine \u00e9tait forc\u00e9ment compliqu\u00e9&#8230; \u00bb<\/p>\n<p>Les avants catalans, domin\u00e9s en m\u00eal\u00e9e et dans le combat par Montpellier, ont \u00e9t\u00e9 piqu\u00e9s dans leur orgueil. \u00ab On a pris le temps de revoir tout ce qui n&#8217;avait pas \u00e9t\u00e9 car il faut l&#8217;assumer, poursuit l&#8217;entra\u00eeneur principal de l&#8217;USAP David Marty. Apr\u00e8s, il s&#8217;agit de trouver des solutions. On ne va pas rester six mois dessus car le Top 14 ne nous attend pas. \u00bb\u00ab Tu ne peux pas rester trop longtemps sur ce qui s&#8217;est pass\u00e9, confirme Patat. Donc on a aussi rapidement parl\u00e9 du prochain contre Clermont, sans trop dramatiser non plus. \u00bb<\/p>\n<p>Quelques focus sont mis sur des secteurs pour le match d&#8217;apr\u00e8s &#8211; \u00ab d\u00e9fense et combat \u00bb, r\u00e9p\u00e8te le pilier de l&#8217;USAP Giorgi Beria avant d&#8217;aller \u00e0 Castres &#8211; quitte \u00e0 en d\u00e9laisser d&#8217;autres. \u00ab Apr\u00e8s Clermont, on a d\u00e9cid\u00e9 d&#8217;all\u00e9ger le disque dur, sur le plan strat\u00e9gique, et d&#8217;axer sur l&#8217;initiative, explique Piqueronies. \u00c7a a eu un impact des deux c\u00f4t\u00e9s : l&#8217;initiative contre Bayonne nous a permis de marquer 50 points mais passer l&#8217;aspect tactique au second plan nous a sans doute co\u00fbt\u00e9 30 points. En fait, mieux on conna\u00eet son groupe, moins on risque de se tromper sur les leviers \u00e0 activer. \u00bb<\/p>\n<p>Certains sont vieux comme le monde ovale et gros comme des maisons de l&#8217;\u00eele de R\u00e9. \u00ab Je pense qu&#8217;ils ont plus regard\u00e9 l&#8217;immobilier \u00e0 la Rochelle et sur l&#8217;\u00eele de R\u00e9 que l&#8217;entra\u00eenement \u00bb, avait cingl\u00e9 Ronan O&#8217;Gara apr\u00e8s une d\u00e9faite \u00e0 Lyon en f\u00e9vrier (28-17). \u00c0 chaud, le manager rochelais, du genre sanguin, avait fait comprendre \u00e0 certains que c&#8217;\u00e9tait leur dernier match avant un bon moment. \u00c0 froid, la raison avait rapidement repris le dessus, ce qui n&#8217;emp\u00eachait pas \u00ab une semaine charg\u00e9e en \u00e9motion et en testost\u00e9rone \u00bb, comme en avait t\u00e9moign\u00e9 quelques jours plus tard le troisi\u00e8me-ligne Judica\u00ebl Cancoriet : \u00ab (Ronan O&#8217;Gara) a su nous piquer quand il fallait mais aussi nous remettre en confiance. On ne peut pas tout le temps taper sur les mecs, \u00e7a ne marche pas. \u00bb<\/p>\n<p>D&#8217;o\u00f9 ces sourires qui reviennent petit \u00e0 petit dans la semaine, une fois que le message est bien re\u00e7u et que les s\u00e9ances d&#8217;entra\u00eenement, parfois plus cors\u00e9es, touchent \u00e0 leur fin. \u00ab On sait o\u00f9 on a merd\u00e9, tout simplement, explique le Perpignanais Giorgi Beria. Donc on s&#8217;y remet et cette semaine, je n&#8217;ai pas vu un seul mec la t\u00eate en bas. \u00bb Les Catalans \u00e0 Castres et les Bayonnais \u00e0 Clermont savent sur quoi ils sont attendus ce samedi apr\u00e8s-midi pour passer un meilleur lundi.<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.lequipe.fr\/Rugby\/Article\/Top-14-comment-se-remettre-en-ordre-apres-une-lourde-defaite\/1509021?xtor=EPR-608&amp;m_i=vHKFgf0yvKdG435ZbuPeq78Wk_4cB8wagEGBkCQ7XkoU1hdrlHUQQSWF4AM3%2BRPNBuEYXIMfnnaskmsvYsqtA%2B7crMCKpUaRfe2IvV&amp;M_BT=26744858836961\">LIRE L&#8217;ARTICLE DANS L&#8217;EQUIPE<\/a><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Equipe: Top14 &#8211; Le d\u00e9but de saison a \u00e9t\u00e9 marqu\u00e9 par certaines roustes. \u00c0 quoi ressemblent les jours qui suivent dans les clubs concern\u00e9s\u00a0?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[23],"tags":[31],"class_list":["post-480","post","type-post","status-publish","format-standard","hentry","category-news","tag-xv","comments-off"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=480"}],"version-history":[{"count":1,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/480\/revisions"}],"predecessor-version":[{"id":482,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/480\/revisions\/482"}],"wp:attachment":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}