
{"id":463,"date":"2024-07-26T12:24:15","date_gmt":"2024-07-26T10:24:15","guid":{"rendered":"https:\/\/play-rugby.com\/?p=463"},"modified":"2025-05-27T13:00:24","modified_gmt":"2025-05-27T11:00:24","slug":"cry-for-me-argentina","status":"publish","type":"post","link":"https:\/\/www.play-rugby.com\/index.php\/2024\/07\/26\/cry-for-me-argentina\/","title":{"rendered":"Cry for Me Argentina&#8230;."},"content":{"rendered":"<h3>VENGEANCE!!!<\/h3>\n<p>Les rugbymen fran\u00e7ais ont surclass\u00e9 l\u2019Argentine 26-14 en quarts de finale du tournoi olympique et verront le dernier jour de comp\u00e9tition, samedi. Une revanche d\u2019autant plus savoureuse qu\u2019elle s\u2019inscrit dans un contexte tendu avec les Argentins<\/p>\n<p>Il fallait bien qu\u2019un jour quelqu\u2019un passe \u00e0 la caisse pour r\u00e9gler la cuenta bien sal\u00e9e laiss\u00e9e sur la table de la France enti\u00e8re par Dibu Martinez et Enzo Fernandez. Au mauvais endroit, au mauvais moment, en l\u2019occurrence au Stade de France en quarts de finale du tournoi olympique de rugby \u00e0 7, les Pumas ont pris de plein fouet les frustrations d\u2019un peuple qui demandait r\u00e9paration pour les torts caus\u00e9s par le gardien de l\u2019\u00e9quipe d\u2019Argentine au Qatar en 2022, et par le milieu de terrain de Chelsea coupable d\u2019avoir entonn\u00e9 un chant raciste avec toute l\u2019Albiceleste, il y a quelques semaines.<\/p>\n<p>Voil\u00e0 deux jours que les Argentins \u00e9taient copieusement hu\u00e9s \u00e0 chaque apparition sur la pelouse dionysienne. Sans trop comprendre, ils s\u2019en \u00e9taient jusqu\u2019ici accommod\u00e9s et m\u00eame amus\u00e9s, \u00e0 l\u2019image du joueur Marcos Moneta. \u00ab Je ne sais pas s\u2019ils sont bless\u00e9s \u00e0 cause de Messi et de la Coupe du Monde ou parce qu\u2019ils ne nous aiment pas. Peut-\u00eatre qu\u2019ils ont peur de nous, je ne sais pas \u00bb<\/p>\n<p>Bof, c\u2019\u00e9tait pas trop la tendance. Dans une d\u00e9claration proph\u00e9tique apr\u00e8s la d\u00e9faite contre les Fidji, dans l\u2019apr\u00e8s-midi, Stephen Parez exhortait les siens \u00e0 \u00ab leur rouler dessus (les Argentins) \u00bb. Non, la peur \u00e9tait clairement dans l\u2019autre camp. Sur Twitter, c\u2019\u00e9tait la peur de jouer le pays h\u00f4te, de se faire voler par l\u2019arbitrage, qui serait forc\u00e9ment acquis \u00e0 la cause des Fran\u00e7ais. \u00ab \u00c7a sera un match \u00e0 8 contre 7 \u00bb, pouvait-on lire entre autres.<\/p>\n<h3>\u00ab Leur montrer que c\u2019\u00e9tait chez nous \u00bb<\/h3>\n<p>Erreur de calcul, c\u2019\u00e9tait un match \u00e0 69.007 contre 7.<\/p>\n<p>Une ambiance de tar\u00e9, empreinte de toute la subjectivit\u00e9 qu\u2019autorise le chauvinisme sportif dans un contexte olympique. A vous foutre les poils d\u00e8s l\u2019annonce du 7 de d\u00e9part. Difficile d\u2019\u00e9valuer \u00e0 quel point les joueurs de l\u2019\u00e9quipe de France ont pu \u00eatre galvanis\u00e9s par le spectacle offert par les supporteurs tricolores en d\u00e9lire, m\u00eame si la premi\u00e8re p\u00e9riode parfaite, le couteau entre les dents, reste un bon indicateur de l\u2019enthousiasme collectif. Et un, et deux, et trois essais. Tous transform\u00e9s, alors que la France piochait dans l\u2019exercice depuis le d\u00e9but du tournoi.<\/p>\n<p>21-0 en une mi-temps. Irr\u00e9el, lunaire, jubilatoire.<\/p>\n<blockquote><p>\u00ab J\u2019avais envie de montrer que je suis chez moi, souligne Andy Timo, l\u2019un des buteurs du soir. Je n\u2019en marque pas beaucoup et du coup je le montre un peu. Surtout que c\u2019est un quart de finale contre l\u2019Argentine, j\u2019avais envie de montrer que c\u2019\u00e9tait chez nous. \u00bb<\/p>\n<p>\u00ab \u00ab Jouer dans un stade comme \u00e7a procure des \u00e9motions que je n\u2019ai jamais v\u00e9cues de ma vie, conc\u00e8de Aaron Grandidier Nkanang en zone mixte. Je n\u2019aurais jamais imagin\u00e9 jouer un jour devant 69.000 personnes. Ce n\u2019est que le quart, il nous reste un grand bout de chemin, mais \u00e7a nous procure des \u00e9motions de malade. J\u2019\u00e9tais presque en larmes \u00e0 la fin du match. Merci aux supporteurs de nous avoir port\u00e9s comme \u00e7a, je n\u2019ai pas les mots. \u00bb \u00bb<\/p><\/blockquote>\n<p>L\u2019effet a fini par s\u2019essouffler en seconde p\u00e9riode, on a m\u00eame cru ces filous d\u2019Argentins partis pour nous climatiser comme jamais. Mais l\u2019entr\u00e9e d\u2019Antoine Dupont, d\u2019abord synonyme de baisse d\u2019intensit\u00e9, s\u2019est finalement av\u00e9r\u00e9e salvatrice. Le Toulousain a d\u2019abord permis de gratter de pr\u00e9cieuses secondes quand les Pumas \u00e9taient revenus \u00e0 sept points, avant de plier le match au buzzer sur une action qui rel\u00e8ve plus de la folie que de l\u2019audace.<\/p>\n<p>Voil\u00e0 les Bleus en demies. Oui, seulement. L\u2019euphorie ambiante et la joie des joueurs fran\u00e7ais apr\u00e8s la rencontre \u00e9taient telle que l\u2019on aurait pu croire l\u2019or olympique d\u00e9j\u00e0 acquis.<\/p>\n<p>Quelque part, ce n\u2019est pas faux. Battre l\u2019Argentine avec panache et selon leurs r\u00e8gles, c\u2019est d\u00e9j\u00e0 une m\u00e9daille en soi.<\/p>\n<blockquote>\n<h1 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.20minutes.fr\/sport\/rugby\/4103095-20240725-jo-2024-rugby-7-montrer-chez-bleus-envie-faire-payer-argentine?xtor=EPR-212-[nl%20morning]---f0359d5b996af3f72d7c57d2776ba1aa@2&amp;utm_source=newsletter&amp;utm_medium=email&amp;utm_campaign=morning&amp;_ope=eyJndWlkIjoiZjAzNTlkNWI5OTZhZjNmNzJkN2M1N2QyNzc2YmExYWEifQ%3D%3D\">MERCI 20minutes!<\/a><\/span><\/h1>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Les rugbymen fran\u00e7ais ont surclass\u00e9 l\u2019Argentine 26-14 en quarts de finale des Jeux. Une revanche d\u2019autant plus savoureuse qu\u2019elle s\u2019inscrit dans un contexte tendu avec les Argentins&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[23],"tags":[46,47,45],"class_list":["post-463","post","type-post","status-publish","format-standard","hentry","category-news","tag-argentine","tag-jeux-olympiques","tag-vii","comments-off"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":1,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"predecessor-version":[{"id":465,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/463\/revisions\/465"}],"wp:attachment":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}