
{"id":460,"date":"2024-07-24T11:31:11","date_gmt":"2024-07-24T09:31:11","guid":{"rendered":"https:\/\/play-rugby.com\/?p=460"},"modified":"2025-05-27T13:00:50","modified_gmt":"2025-05-27T11:00:50","slug":"vii-origines-et-regles-du-rugby-a-7-aux-jeux-olympiques","status":"publish","type":"post","link":"https:\/\/www.play-rugby.com\/index.php\/2024\/07\/24\/vii-origines-et-regles-du-rugby-a-7-aux-jeux-olympiques\/","title":{"rendered":"VII: Origines et R\u00e8gles du Rugby \u00e0 7 aux Jeux Olympiques"},"content":{"rendered":"<p>Alors que l&#8217;\u00c9quipe de France d\u00e9marre le Tournoi Olympique le mercredi 24 juillet, d\u00e9couvrez en plus sur ce sport encore trop m\u00e9connu dans l&#8217;Hexagone<\/p>\n<h4 class=\"mb-xs@xs font-base heading-xxs@xs\"><span style=\"color: #ff0000;\"><em><strong>L&#8217;essentiel<\/strong><\/em><\/span><\/h4>\n<ul class=\"list-with-diode list-with-diode--rubric-theme-sport\">\n<li><span style=\"color: #ff0000;\"><em><strong>Le Sevens a remplac\u00e9 le rugby \u00e0 XV aux JO, notamment en raison de son format.<\/strong><\/em><\/span><\/li>\n<li><span style=\"color: #ff0000;\"><em><strong>Les rencontres sont plus courtes et l&#8217;intensit\u00e9 d\u00e9cupl\u00e9e.<\/strong><\/em><\/span><\/li>\n<li><span style=\"color: #ff0000;\"><em><strong>Attirer un jeune public est aussi une des missions de l&#8217;introduction du rugby \u00e0 7 aux Jeux Olympiques.<\/strong><\/em><\/span><\/li>\n<\/ul>\n<p>Invent\u00e9 en Grande-Bretagne entre 1845 et 1848, le rugby est un des sports les plus populaires au monde. En 1871 se tient le premier match international et la F\u00e9d\u00e9ration internationale de rugby voit le jour en 1886. M\u00eame si le rugby a \u00e9t\u00e9 un sport olympique, en 1900, 1908, 1920 et 1924, il s&#8217;agissait d&#8217;une discipline se pratiquant \u00e0 15. Il a disparu des JO entre 1924 et 2016, o\u00f9 il a \u00e9t\u00e9 introduit \u00e0 Rio, mais sous la forme de rugby \u00e0 7. Savez-vous pour quelles raisons ?<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.20minutes.fr\/sport\/rugby\/4102740-20240724-origines-regles-rugby-7-jeux-olympiques?xtor=EPR-212-[nl%20sport]---f0359d5b996af3f72d7c57d2776ba1aa@2&amp;utm_source=newsletter&amp;utm_medium=email&amp;utm_campaign=sports&amp;_ope=eyJndWlkIjoiZjAzNTlkNWI5OTZhZjNmNzJkN2M1N2QyNzc2YmExYWEifQ%3D%3D\">Lire l&#8217;Article sur 20minutes.fr<\/a><\/h1>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que l&#8217;\u00c9quipe de France d\u00e9marre le Tournoi Olympique le mercredi 24 juillet, d\u00e9couvrez en plus sur ce sport encore trop m\u00e9connu dans l&#8217;Hexagone L&#8217;essentiel Le Sevens a remplac\u00e9 le<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-460","post","type-post","status-publish","format-standard","hentry","category-news","comments-off"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":1,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/460\/revisions"}],"predecessor-version":[{"id":462,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/posts\/460\/revisions\/462"}],"wp:attachment":[{"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/media?parent=460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/categories?post=460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.play-rugby.com\/index.php\/wp-json\/wp\/v2\/tags?post=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}